{"id":2891,"date":"2019-04-30T11:05:09","date_gmt":"2019-04-30T14:05:09","guid":{"rendered":"http:\/\/saolourencodaserra.sp.gov.br\/novo\/?p=2891"},"modified":"2019-05-25T00:32:22","modified_gmt":"2019-05-25T03:32:22","slug":"adiado-cadastramento-para-emissao-de-notas-fiscais-eletronicas","status":"publish","type":"post","link":"http:\/\/saolourencodaserra.sp.gov.br\/novo\/adiado-cadastramento-para-emissao-de-notas-fiscais-eletronicas\/","title":{"rendered":"ADIADO PARA 20\/05 &#8211; Cadastramento para Emiss\u00e3o de Notas Fiscais Eletr\u00f4nicas"},"content":{"rendered":"<p>Devido a quest\u00f5es t\u00e9cnicas no desenvolvimento do sistema, a Prefeitura ter\u00e1 que <strong>adiar o lan\u00e7amento<\/strong> do novo sistema para emiss\u00e3o de Notas Fiscais Eletr\u00f4nicas <strong>para 20\/05<\/strong>.<\/p>\n<p>Informamos que a partir de\u00a0<strong>20 de maio de 2019<\/strong>, a\u00a0<strong>Prefeitura Municipal de S\u00e3o Louren\u00e7o da Serra<\/strong>, passar\u00e1 a utilizar outro ambiente para emiss\u00e3o de\u00a0<strong>Notas Fiscais Eletr\u00f4nicas<\/strong>, e para isso, toda as empresas cadastradas e emissoras de notas, dever\u00e3o realizar um novo credenciamento neste ambiente.<\/p>\n<p>Para se credenciar\u00a0<a href=\"http:\/\/nfse.saolourencodaserra.sp.gov.br\/NotaFiscal\/index.php?codCidIni=5447\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>CLIQUE AQUI E ACESSE<\/strong><\/a>. Ap\u00f3s acessar basta clicar na op\u00e7\u00e3o\u00a0<a href=\"http:\/\/nfse.saolourencodaserra.sp.gov.br\/NotaFiscal\/senhaWeb.php\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>\u201cCredenciamento\u201d<\/strong><\/a>.<\/p>\n<p>Para mais informa\u00e7\u00f5es e\/ou dificuldades, encaminhe um email para\u00a0<a href=\"mailto:atendimentoiss@saolourencodaserra.sp.gov.br\">atendimentoiss@saolourencodaserra.sp.gov.br<\/a><\/p>\n<p>Lembrando que caso voc\u00ea n\u00e3o realize o devido credenciamento, a partir de 20 de maio de 2019 voc\u00ea n\u00e3o conseguir\u00e1 mais emitir notas fiscais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Devido a quest\u00f5es t\u00e9cnicas no desenvolvimento do sistema, a Prefeitura ter\u00e1 que adiar o lan\u00e7amento do novo sistema para emiss\u00e3o de Notas Fiscais Eletr\u00f4nicas para 20\/05. Informamos que a partir de\u00a020 de maio de 2019, a\u00a0Prefeitura Municipal de S\u00e3o Louren\u00e7o da Serra, passar\u00e1 a utilizar outro ambiente para emiss\u00e3o de\u00a0Notas Fiscais Eletr\u00f4nicas, e para isso, &#8230;<\/p>\n","protected":false},"author":1,"featured_media":2892,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[21,67,332],"tags":[],"_links":{"self":[{"href":"http:\/\/saolourencodaserra.sp.gov.br\/novo\/wp-json\/wp\/v2\/posts\/2891"}],"collection":[{"href":"http:\/\/saolourencodaserra.sp.gov.br\/novo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/saolourencodaserra.sp.gov.br\/novo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/saolourencodaserra.sp.gov.br\/novo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/saolourencodaserra.sp.gov.br\/novo\/wp-json\/wp\/v2\/comments?post=2891"}],"version-history":[{"count":0,"href":"http:\/\/saolourencodaserra.sp.gov.br\/novo\/wp-json\/wp\/v2\/posts\/2891\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/saolourencodaserra.sp.gov.br\/novo\/wp-json\/wp\/v2\/media\/2892"}],"wp:attachment":[{"href":"http:\/\/saolourencodaserra.sp.gov.br\/novo\/wp-json\/wp\/v2\/media?parent=2891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/saolourencodaserra.sp.gov.br\/novo\/wp-json\/wp\/v2\/categories?post=2891"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/saolourencodaserra.sp.gov.br\/novo\/wp-json\/wp\/v2\/tags?post=2891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}